{"id":5075,"date":"2021-11-05T14:09:25","date_gmt":"2021-11-05T17:09:25","guid":{"rendered":"https:\/\/www.petrini.com.ar\/?p=5075"},"modified":"2021-11-05T14:09:25","modified_gmt":"2021-11-05T17:09:25","slug":"el-dato-de-la-semana-7","status":"publish","type":"post","link":"https:\/\/www.petrini.com.ar\/en\/el-dato-de-la-semana-7\/","title":{"rendered":"El dato de la semana"},"content":{"rendered":"<p><strong>COMIENZA EL TAPERING Y LA TASA NO SE TOCA<\/strong><br \/>\nFinalmente la FED resolvi\u00f3 lo que ven\u00eda anticipando: comenzar\u00e1 a reducir su programa de compra de activos (bonos del Tesoro y letras hipotecarias) en el mes de noviembre, a un ritmo de 15.000 millones de d\u00f3lares mensuales. No obstante, dej\u00f3 la puerta abierta a acelerar la reducci\u00f3n de sus compras &#8220;si los cambios en las perspectivas econ\u00f3micas lo justifican&#8221;. En este sentido, los analistas interpretan que ha ganado flexibilidad para reducir a\u00fan m\u00e1s sus compras si la inflaci\u00f3n sigue siendo demasiado elevada durante el pr\u00f3ximo a\u00f1o.<br \/>\nAl respecto, Jerome Powell reconoci\u00f3 que los precios hab\u00edan subido m\u00e1s de lo que esperaban pero responsabiliz\u00f3 a las distorsiones en las cadenas de suministros provocadas por la pandemia, un factor que la Fed no puede controlar.<br \/>\nFinalmente, tambi\u00e9n resolvi\u00f3 no subir los tipos de inter\u00e9s hasta llegar al pleno empleo, lo que podr\u00eda lograrse durante el segundo semestre del pr\u00f3ximo a\u00f1o.<br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2021\/11\/Govt-10Y-UST-1024x374.png\" alt=\"\" width=\"770\" height=\"281\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>COMIENZA EL TAPERING Y LA TASA NO SE TOCA Finalmente la FED resolvi\u00f3 lo que ven\u00eda anticipando: comenzar\u00e1 a reducir su programa de compra de activos (bonos del Tesoro y letras hipotecarias) en el mes de noviembre, a un ritmo de 15.000 millones de d\u00f3lares mensuales. No obstante, dej\u00f3 la puerta abierta a acelerar la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103],"tags":[],"class_list":["post-5075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/5075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/comments?post=5075"}],"version-history":[{"count":0,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/5075\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media\/3993"}],"wp:attachment":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media?parent=5075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/categories?post=5075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/tags?post=5075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}