{"id":4755,"date":"2021-10-25T09:56:06","date_gmt":"2021-10-25T12:56:06","guid":{"rendered":"https:\/\/www.petrini.com.ar\/?p=4755"},"modified":"2021-10-25T09:56:06","modified_gmt":"2021-10-25T12:56:06","slug":"claves-para-la-semana-7","status":"publish","type":"post","link":"https:\/\/www.petrini.com.ar\/en\/claves-para-la-semana-7\/","title":{"rendered":"Claves para la semana"},"content":{"rendered":"<p>En los mercados internacionales, la atenci\u00f3n esta semana seguir\u00e1 puesta en los balances del tercer trimestre, ya que en los pr\u00f3ximos d\u00edas se conocer\u00e1n los resultados de Facebook, Alphabet, Amazon, AMD, Boing, Exxon, Google y Microsoft, entre otras. En tanto, el jueves 28 se publica el PBI estadounidense correspondiente al tercer trimestre.<\/p>\n<p>Por otro lado, en el Viejo Continente habr\u00e1 novedades sobre c\u00f3mo avanzan los precios en la Zona Euro y reuni\u00f3n sobre tasas del Banco Central Europeo.<\/p>\n<p>En Brasil, se conocer\u00e1 la tasa de desempleo. Tambi\u00e9n durante la semana, los directivos del Banco Central comunicar\u00e1n su decisi\u00f3n sobre la tasa de inter\u00e9s para el pr\u00f3ximo mes<\/p>\n<p>En nuestro pa\u00eds, esta semana el Gobierno buscar\u00e1 encaminar el cierre del programa financiero de 2021 con la \u00faltima licitaci\u00f3n en pesos de octubre. Se tratar\u00e1 de una subasta clave, ya que el 29 de octubre vencen m\u00e1s de $ 264 mil millones. Por este motivo, se espera que para el mi\u00e9rcoles el Ministerio de Econom\u00eda ofrezca una canasta seductora de instrumentos para captar el exceso de circulante que est\u00e1 presionando a la inflaci\u00f3n.<\/p>\n<p><a href=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2021\/10\/Claves-de-la-semana-1.jpg-1-1.bmp\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4756 size-full\" src=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2021\/10\/Claves-de-la-semana-1.jpg-1-1.bmp\" alt=\"\" width=\"543\" height=\"201\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>En los mercados internacionales, la atenci\u00f3n esta semana seguir\u00e1 puesta en los balances del tercer trimestre, ya que en los pr\u00f3ximos d\u00edas se conocer\u00e1n los resultados de Facebook, Alphabet, Amazon, AMD, Boing, Exxon, Google y Microsoft, entre otras. En tanto, el jueves 28 se publica el PBI estadounidense correspondiente al tercer trimestre. Por otro lado, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103],"tags":[],"class_list":["post-4755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/4755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4755"}],"version-history":[{"count":0,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/4755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media\/3994"}],"wp:attachment":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}