{"id":4718,"date":"2021-10-22T17:28:16","date_gmt":"2021-10-22T20:28:16","guid":{"rendered":"https:\/\/www.petrini.com.ar\/?p=4718"},"modified":"2021-10-22T17:28:16","modified_gmt":"2021-10-22T20:28:16","slug":"el-dato-de-la-semana-6","status":"publish","type":"post","link":"https:\/\/www.petrini.com.ar\/en\/el-dato-de-la-semana-6\/","title":{"rendered":"El dato de la semana"},"content":{"rendered":"<p><strong>LOCAL<\/strong><\/p>\n<p>Sin lugar a dudas, en el plano local, el establecimiento de un congelamiento de precios en la econom\u00eda sin acuerdo con el empresariado, sum\u00f3 incertidumbre en un contexto econ\u00f3mico, social y pol\u00edtico que ya ven\u00eda enrarecido desde las PASO. Las diferentes cotizaciones del d\u00f3lar reflejaron este clima mostrando cotizaciones m\u00e1ximas, a pesar de que el Banco Central obtuvo saldo comprador la mayor parte de la semana.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4725 size-full\" src=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2021\/10\/Dato-de-la-semana-1-1.png\" alt=\"\" width=\"1004\" height=\"337\" \/><\/p>\n<p><strong>INTERNACIONAL<\/strong><\/p>\n<p>La incertidumbre en nuestro mercado se profundiz\u00f3 con un contexto internacional igualmente vol\u00e1til. La posibilidad de un giro en las condiciones financieras a nivel global complica a la deuda emergente. A las tasas largas de EEU en suba, \u00a0se sumaron Turqu\u00eda y Brasil para aportar m\u00e1s volatilidad. La lira turca se desplom\u00f3 casi 10% en un mes, mientras que el real acumula una ca\u00edda de m\u00e1s del 5% frente al d\u00f3lar en las \u00faltimas ruedas. El dato positivo fue que la desarrollista china, Evergrande, habr\u00eda evitado el default de uno de sus bonos pagando sobre la hora antes que venciera el plazo de gracia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4722 size-large aligncenter\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2021\/10\/US-10-1024x337.png\" alt=\"\" width=\"770\" height=\"253\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>LOCAL Sin lugar a dudas, en el plano local, el establecimiento de un congelamiento de precios en la econom\u00eda sin acuerdo con el empresariado, sum\u00f3 incertidumbre en un contexto econ\u00f3mico, social y pol\u00edtico que ya ven\u00eda enrarecido desde las PASO. Las diferentes cotizaciones del d\u00f3lar reflejaron este clima mostrando cotizaciones m\u00e1ximas, a pesar de que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3993,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103],"tags":[],"class_list":["post-4718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"_links":{"self":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/4718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/comments?post=4718"}],"version-history":[{"count":0,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/4718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media\/3993"}],"wp:attachment":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media?parent=4718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/categories?post=4718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/tags?post=4718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}