{"id":28544,"date":"2026-05-12T14:21:37","date_gmt":"2026-05-12T14:21:37","guid":{"rendered":"https:\/\/www.petrini.com.ar\/?p=28544"},"modified":"2026-05-12T14:21:39","modified_gmt":"2026-05-12T14:21:39","slug":"nueva-emision-de-letras-y-bonos-del-tesoro-65","status":"publish","type":"post","link":"https:\/\/www.petrini.com.ar\/en\/nueva-emision-de-letras-y-bonos-del-tesoro-65\/","title":{"rendered":"Nueva emisi\u00f3n de Letras y Bonos del Tesoro"},"content":{"rendered":"<p>En esta oportunidad, la Secretar\u00eda de Finanzas ofrece en este llamado a licitaci\u00f3n una combinaci\u00f3n de letras capitalizables a tasa fija, letras capitalizables a tasa TAMAR, bonos ajustables por CER, bonos duales CER\/TAMAR, letras vinculadas al d\u00f3lar estadounidense y bono en d\u00f3lares estadounidenses.<\/p>\n\n\n\n<p>Fecha de licitaci\u00f3n: Mi\u00e9rcoles 13 de mayo de 2026 de 10:00 a 15:00<\/p>\n\n\n\n<p><em>Para el caso de los BONAR 2027 (AO27) y BONAR 2028 (AO28) habr\u00e1 una segunda vuelta el mi\u00e9rcoles 29 de abril de 2026 de 10:00 a 15:00 (T+1), que ser\u00e1 por adhesi\u00f3n con un \u00fanico pliego al precio de corte.<\/em><\/p>\n\n\n\n<p>Fecha de liquidaci\u00f3n: Viernes 15 mayo de 2026 (T+2)<\/p>\n\n\n\n<p>Detallamos las caracter\u00edsticas de los instrumentos a emitir:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.08.47-AM.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"912\" height=\"456\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.08.47-AM.jpeg\" alt=\"\" class=\"wp-image-28545\" srcset=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.08.47-AM.jpeg 912w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.08.47-AM-300x150.jpeg 300w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.08.47-AM-768x384.jpeg 768w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.08.47-AM-18x9.jpeg 18w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.08.47-AM-600x300.jpeg 600w\" sizes=\"auto, (max-width: 912px) 100vw, 912px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.15.07-AM.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"815\" height=\"593\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.15.07-AM.jpeg\" alt=\"\" class=\"wp-image-28546\" style=\"width:839px;height:auto\" srcset=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.15.07-AM.jpeg 815w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.15.07-AM-300x218.jpeg 300w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.15.07-AM-768x559.jpeg 768w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.15.07-AM-16x12.jpeg 16w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-10.15.07-AM-600x437.jpeg 600w\" sizes=\"auto, (max-width: 815px) 100vw, 815px\" \/><\/a><\/figure>\n\n\n\n<p><em>* Pesos al tipo de cambio de referencia publicado por el BCRA en<br>funci\u00f3n de la Comunicaci\u00f3n \u201cA\u201d 3500 correspondiente al d\u00eda<br>h\u00e1bil previo a la fecha de licitaci\u00f3n (T-1)<\/em><\/p>\n\n\n\n<p><em>** Es el tipo de cambio de referencia publicado por el BCRA en<br>funci\u00f3n de la Comunicaci\u00f3n \u201cA\u201d 3500 correspondiente al tercer d\u00eda<br>h\u00e1bil previo a la fecha de pago<\/em><\/p>\n\n\n\n<p><em>*** Con un precio m\u00e1ximo de USD 1016.66<\/em><\/p>\n\n\n\n<p>Para m\u00e1s informaci\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comunicate por tel\u00e9fono: +54 (351) 423-0048 o por email\u00a0<a href=\"mailto:info@petrini.com.ar\">info@petrini.com.ar<\/a><\/li>\n\n\n\n<li>O coordin\u00e1 una reuni\u00f3n en nuestras oficinas comerciales: 25 de Mayo 267 \u2013 Piso 3 \u2013 C\u00f3rdoba, Argentina.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>En esta oportunidad, la Secretar\u00eda de Finanzas ofrece en este llamado a licitaci\u00f3n una combinaci\u00f3n de letras capitalizables a tasa fija, letras capitalizables a tasa TAMAR, bonos ajustables por CER, bonos duales CER\/TAMAR, letras vinculadas al d\u00f3lar estadounidense y bono en d\u00f3lares estadounidenses. Fecha de licitaci\u00f3n: Mi\u00e9rcoles 13 de mayo de 2026 de 10:00 a [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":2904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[],"class_list":["post-28544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emisiones"],"_links":{"self":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/28544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/comments?post=28544"}],"version-history":[{"count":2,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/28544\/revisions"}],"predecessor-version":[{"id":28548,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/28544\/revisions\/28548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media\/2904"}],"wp:attachment":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media?parent=28544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/categories?post=28544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/tags?post=28544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}