{"id":15984,"date":"2023-01-23T09:27:20","date_gmt":"2023-01-23T12:27:20","guid":{"rendered":"https:\/\/www.petrini.com.ar\/?p=15984"},"modified":"2023-01-23T09:27:20","modified_gmt":"2023-01-23T12:27:20","slug":"trade-idea-con-bonos-globales","status":"publish","type":"post","link":"https:\/\/www.petrini.com.ar\/en\/trade-idea-con-bonos-globales\/","title":{"rendered":"Trade idea con Bonos Globales"},"content":{"rendered":"<p>La decisi\u00f3n del Ministro de Econom\u00eda de recomprar bonos en d\u00f3lares a trav\u00e9s de operaciones de mercado abierto encomendadas al BCRA, ha generado movimientos en los precios de los bonos provocando oportunidades de arbitrajes.<\/p>\n<p>Bonares y Globales comparten similares condiciones de repago (excepto los 2038 y 2041), pero difieren respecto a la ley aplicable: los Bonares fueron emitidos bajo Ley Argentina y Globales, bajo Ley Extranjera (Nueva York). Los t\u00edtulos p\u00fablicos m\u00e1s utilizados para realizar la operatoria de d\u00f3lar MEP y d\u00f3lar Cable son los Bonar 2030 (AL30) y los Globales 2030 (GD30). Este \u00faltimo tambi\u00e9n es el m\u00e1s empleado para acceder al d\u00f3lar contado con liquidaci\u00f3n (CCL).<\/p>\n<p>Debido a las intervenciones del Gobierno vendiendo y comprando bonos para sostener los precios, se ampl\u00edan las disparidades de cotizaciones. Es aqu\u00ed donde aparecen las oportunidades de arbitrajes ya que los m\u00e1s empleados para acceder a d\u00f3lares financieros subieron de precio respecto del resto. En los gr\u00e1ficos se ve claramente que las paridades entre GD30\/GD41 y GD30\/GD38 est\u00e1n en m\u00ednimos. El GD30 cotiza a 36 d\u00f3lares mientras que el GD41 cotiza a 33. Esto permite comprar un 10% m\u00e1s de nominales, a lo que se suma que el GD41 paga un cup\u00f3n de renta m\u00e1s alto (3.5% vs\u00a0 0.5%).<\/p>\n<p>Para quien tenga GD30, podr\u00eda ser un buen momento de venderlos y posicionarse en GD41 o GD38.\u00a0 Las implicancias de vender los 30s y comprar bonos m\u00e1s largos como los arriba mencionados implica alargar duration pero mejorar mucho el flujo a percibir debido a los cupones m\u00e1s altos y tener exposici\u00f3n a bonos indenture 2005 (CACs con porcentajes m\u00e1s altos)<\/p>\n<p>Tambi\u00e9n se podr\u00eda evaluar la alternativa de canjear por los BONARES\u00a0 en lugar de Globales donde la brecha es a\u00fan mayor.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD41-1024x405.png\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" srcset=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD41-1024x405.png 1024w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD41-300x119.png 300w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD41-768x303.png 768w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD41-570x225.png 570w, http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD41-1-1.png 1278w\" alt=\"\" width=\"770\" height=\"305\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD38-1024x413.png\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" srcset=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD38-1024x413.png 1024w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD38-300x121.png 300w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD38-768x310.png 768w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD38-570x230.png 570w, http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/GD30-GD38-1-1.png 1271w\" alt=\"\" width=\"770\" height=\"311\" \/><\/p>\n<p>La situaci\u00f3n en los Bonares no es la misma dado que los movimientos de precios han sido mucho m\u00e1s marcados en los Globales, pero si uno analiza los spreads entre Bonares, los mismos se han modificado comparados con diciembre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AL41-1024x407.png\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" srcset=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AL41-1024x407.png 1024w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AL41-300x119.png 300w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AL41-768x305.png 768w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AL41-570x226.png 570w, http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AL41-1-1.png 1276w\" alt=\"\" width=\"770\" height=\"306\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AE38-1024x408.png\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" srcset=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AE38-1024x408.png 1024w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AE38-300x120.png 300w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AE38-768x306.png 768w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AE38-570x227.png 570w, http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/AL30-AE38-1-1.png 1287w\" alt=\"\" width=\"770\" height=\"307\" \/><\/p>\n<p><b>Precios al viernes 20 de enero a las 17hs.<\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/Precios-20ene2023-1-1.png\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" srcset=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/Precios-20ene2023-1-1.png 716w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/Precios-20ene2023-300x175.png 300w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/Precios-20ene2023-570x332.png 570w\" alt=\"\" width=\"716\" height=\"417\" \/><\/p>\n<p><b>La informaci\u00f3n contenida en este documento no pretende ser una oferta, invitaci\u00f3n o solicitud para comprar o vender valores negociables, y se ha obtenido de fuentes confiables a nuestro criterio, pero no est\u00e1 garantizada su precisi\u00f3n o integridad. El documento, as\u00ed como la informaci\u00f3n, opiniones, estimaciones y recomendaciones aqu\u00ed expresadas, han sido elaborados por Petrini Valores S.A. para brindar a sus clientes informaci\u00f3n general y est\u00e1n sujetos a cambios sin previo aviso.\u00a0<\/b><\/p>\n<p><b>Petrini Valores S.A. no es responsable de dar aviso de tales cambios o de actualizar el contenido del mismo. El documento y su contenido no constituyen una oferta, invitaci\u00f3n o solicitud para comprar o suscribir valores u otros instrumentos, o para invertir o desinvertir. Los inversores que tengan acceso al documento deben ser conscientes de que los valores, instrumentos o inversiones a los que se refiere pueden no ser adecuados para ellos debido a sus objetivos de inversi\u00f3n espec\u00edficos, posiciones financieras o perfiles de riesgo, ya que estos no se han tenido en cuenta para preparar el informe. Por tanto, los inversores deben tomar sus propias decisiones de inversi\u00f3n teniendo en cuenta dichas circunstancias y obtener el asesoramiento especializado que sea necesario.<\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>La decisi\u00f3n del Ministro de Econom\u00eda de recomprar bonos en d\u00f3lares a trav\u00e9s de operaciones de mercado abierto encomendadas al BCRA, ha generado movimientos en los precios de los bonos provocando oportunidades de arbitrajes. Bonares y Globales comparten similares condiciones de repago (excepto los 2038 y 2041), pero difieren respecto a la ley aplicable: los [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2901,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111],"tags":[],"class_list":["post-15984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trade-idea"],"_links":{"self":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/15984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/comments?post=15984"}],"version-history":[{"count":0,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/15984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media\/2901"}],"wp:attachment":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media?parent=15984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/categories?post=15984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/tags?post=15984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}