{"id":15962,"date":"2023-01-20T17:20:57","date_gmt":"2023-01-20T20:20:57","guid":{"rendered":"https:\/\/www.petrini.com.ar\/?p=15962"},"modified":"2023-01-20T17:20:57","modified_gmt":"2023-01-20T20:20:57","slug":"nueva-emision-de-irsa","status":"publish","type":"post","link":"https:\/\/www.petrini.com.ar\/en\/nueva-emision-de-irsa\/","title":{"rendered":"Nueva emisi\u00f3n de IRSA"},"content":{"rendered":"<p>Petrini Valores, en su car\u00e1cter de colocador, comunica los principales t\u00e9rminos y condiciones de la nueva emisi\u00f3n de Obligaciones Negociables de IRSA.<\/p>\n<p>Hacer click en cada documento para acceder a:<\/p>\n<p>&#8211;<a href=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/IRSA-Suplemento-ON-Clase-XV-20.01.2023-VF_Resumido-1.pdf\">Suplemento de Prospecto Resumido de ON Clase XV<\/a><\/p>\n<p>&#8211;<a href=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/IRSA-Aviso-de-Suscripcion-ON-Clase-XV-20.01.23-VF-1.pdf\">Aviso de Suscripci\u00f3n de ON Clase XV<\/a><\/p>\n<p>&#8211;<a href=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/IRSA-Suplemento-ON-Clase-XVI-20.01.2023-VF_Resumido-1.pdf\">Suplemento de Prospecto Resumido de ON Clase XVI<\/a><\/p>\n<p>&#8211;<a href=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/IRSA-Aviso-de-Suscripcion-ON-Clase-XVI-20.01.23-VF-1.pdf\">Aviso de Suscripci\u00f3n de ON Clase XVI<\/a><\/p>\n<p>Per\u00edodo de Difusi\u00f3n: desde el Lunes 23\/01 al Mi\u00e9rcoles 25\/01<br \/>Licitaci\u00f3n: Jueves 26 de Enero de 10.00hs a 16.00hs<br \/>Emisi\u00f3n y liquidaci\u00f3n: Martes 31 de Enero<\/p>\n<p>Debajo detallamos condiciones de emisi\u00f3n:<\/p>\n<p><a href=\"https:\/\/www.petrini.com.ar\/en\/nueva-emision-de-irsa\/whatsapp-image-2023-01-20-at-4-44-17-pm\/\" rel=\"attachment wp-att-15971\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-20-at-4.44.17-PM-1-1.jpeg\" alt=\"\" width=\"566\" height=\"459\" \/><\/a><\/p>\n<p>Para m\u00e1s informaci\u00f3n:<\/p>\n<p>&#x2714; Ingres\u00e1 a nuestra web www.petrini.com.ar.<\/p>\n<p>&#x2714; Comunicate por tel\u00e9fono: +54 (351) 423-0048 o por email en info@petrini.com.ar<\/p>\n<p>&#x2714; O coordin\u00e1 por privado una reuni\u00f3n en nuestra oficinas comerciales: 25 de Mayo 267 \u2013 Piso 3 \u2013 C\u00f3rdoba, Argentina.<\/p>\n<p><strong>RESULTADOS DE LA LICITACI\u00d3N<\/strong><\/p>\n<p>La empresa dio a conocer los resultados de la licitaci\u00f3n llevada a cabo el d\u00eda 26 de enero de 2023, en la que Petrini Valores actu\u00f3 como Agente Colocador.<\/p>\n<p>Para acceder al comunicado oficial de la empresa:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/IRSA_Aviso-de-Resultados-ON-Clase-XV.pdf\">Resultado Clase XV<\/a><\/li>\n<li><a href=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2023\/01\/IRSA_Aviso-de-Resultados-ON-Clase-XVI.pdf\">Resultado Clase XVI<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Petrini Valores, en su car\u00e1cter de colocador, comunica los principales t\u00e9rminos y condiciones de la nueva emisi\u00f3n de Obligaciones Negociables de IRSA. Hacer click en cada documento para acceder a: &#8211;Suplemento de Prospecto Resumido de ON Clase XV &#8211;Aviso de Suscripci\u00f3n de ON Clase XV &#8211;Suplemento de Prospecto Resumido de ON Clase XVI &#8211;Aviso de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[],"class_list":["post-15962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emisiones"],"_links":{"self":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/15962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/comments?post=15962"}],"version-history":[{"count":0,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/15962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media\/2904"}],"wp:attachment":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media?parent=15962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/categories?post=15962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/tags?post=15962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}