{"id":15401,"date":"2022-11-14T12:33:05","date_gmt":"2022-11-14T15:33:05","guid":{"rendered":"https:\/\/www.petrini.com.ar\/?p=15401"},"modified":"2022-11-14T12:33:05","modified_gmt":"2022-11-14T15:33:05","slug":"claves-de-la-semana-5","status":"publish","type":"post","link":"https:\/\/www.petrini.com.ar\/en\/claves-de-la-semana-5\/","title":{"rendered":"Claves de la semana"},"content":{"rendered":"<p>La semana que comienza hoy viene cargada de datos macroecon\u00f3micos en todo el mundo, aunque los ojos est\u00e9n puestos en la cumbre del G20 que se llevar\u00e1 a cabo los d\u00edas 15 y 16. Probablemente la reuni\u00f3n del presidente estadounidense, Joe Biden, con su hom\u00f3logo chino, Xi Jinping, sea lo m\u00e1s destacado de la cumbre, al tratarse del primer encuentro cara a cara desde que Biden accedi\u00f3 al cargo hace ya dos a\u00f1os.<\/p>\n<p><strong>Inflaci\u00f3n<\/strong><\/p>\n<p>As\u00ed, y en el primer caso, destacar\u00edamos la publicaci\u00f3n el d\u00eda martes en EEUU del \u00edndice de precios de la producci\u00f3n (IPP), que ser\u00eda muy positivo que corrobore tambi\u00e9n la moderaci\u00f3n en octubre de la inflaci\u00f3n a nivel f\u00e1brica.<\/p>\n<p>Argentina difunde la cifra de inflaci\u00f3n de octubre, despu\u00e9s de que en septiembre superara el 80 % interanual, tasas alt\u00edsimas en el marco de incertidumbre econ\u00f3mica que vive el pa\u00eds.<\/p>\n<p>El d\u00eda jueves se conocer\u00e1 la inflaci\u00f3n minorista en la eurozona donde el \u00faltimo registr\u00f3 super\u00f3 el 10% anual, lo que ha empujado al BCE a subir la tasa de referencia para intentar corregirla.<\/p>\n<p><strong>Producci\u00f3n industrial<\/strong><\/p>\n<p>Al comienzo de la semana tanto la eurozona como China dar\u00e1n a conocer sus niveles de producci\u00f3n industrial. Las previsiones de Oxford Economics apuntan a una recesi\u00f3n en la eurozona entre el cuarto trimestre de este a\u00f1o y el primero de 2023, liderada por una considerable contracci\u00f3n de la producci\u00f3n industrial.<\/p>\n<p>Por su parte, EEUU tambi\u00e9n publicar\u00e1 el dato de octubre junto a los inventarios empresariales.<\/p>\n<p><strong>Otros datos macroecon\u00f3micos<\/strong><\/p>\n<p>Las cifras de\u00a0ventas minoristas\u00a0en EEUU de octubre del mi\u00e9rcoles deber\u00edan proporcionar informaci\u00f3n sobre c\u00f3mo les va a los consumidores antes de la temporada clave de compras navide\u00f1as ante una inflaci\u00f3n hist\u00f3ricamente elevada. Sumado a ello, esta semana se concentran gran n\u00famero de resultados del sector de la distribuci\u00f3n minorista, con empresas como Home Depot (HD-US), Lowe\u2019s (LOW-US), Walmart (WMT-US), Target (TGT-US) y Macy\u2019s (M-US). Lo que digan los gestores de esas empresas ser\u00e1 en gran medida extrapolable a muchas otras compa\u00f1\u00edas y sectores de actividad.<\/p>\n<p>Se dar\u00e1n a conocer tambi\u00e9n datos acerca de viviendas: permisos, inicios de construcci\u00f3n y ventas. Es probable que reflejen el impacto actual de la r\u00e1pida subida de tasas de inter\u00e9s en lo que va del a\u00f1o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2022\/11\/Calendario-1-1.png\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" srcset=\"http:\/\/www.petrini.com.ar\/wp-content\/uploads\/2022\/11\/Calendario-1-1.png 544w, https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2022\/11\/Calendario-300x266.png 300w\" alt=\"\" width=\"544\" height=\"482\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>La semana que comienza hoy viene cargada de datos macroecon\u00f3micos en todo el mundo, aunque los ojos est\u00e9n puestos en la cumbre del G20 que se llevar\u00e1 a cabo los d\u00edas 15 y 16. Probablemente la reuni\u00f3n del presidente estadounidense, Joe Biden, con su hom\u00f3logo chino, Xi Jinping, sea lo m\u00e1s destacado de la cumbre, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100],"tags":[],"class_list":["post-15401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercados"],"_links":{"self":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/15401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/comments?post=15401"}],"version-history":[{"count":0,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/15401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media\/3994"}],"wp:attachment":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media?parent=15401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/categories?post=15401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/tags?post=15401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}