{"id":12132,"date":"2022-06-27T13:41:55","date_gmt":"2022-06-27T16:41:55","guid":{"rendered":"https:\/\/www.petrini.com.ar\/?p=12132"},"modified":"2022-06-27T13:41:55","modified_gmt":"2022-06-27T16:41:55","slug":"nueva-emision-de-letras-y-bonos-del-tesoro-19","status":"publish","type":"post","link":"https:\/\/www.petrini.com.ar\/en\/nueva-emision-de-letras-y-bonos-del-tesoro-19\/","title":{"rendered":"Nueva emisi\u00f3n de Letras y Bonos del Tesoro"},"content":{"rendered":"<p>En esta oportunidad, el Ministerio de Econom\u00eda de la Naci\u00f3n licita Letras en Pesos, Bonos D\u00f3lar Linked y Lecer del Tesoro Nacional.<\/p>\n<p>Fecha de licitaci\u00f3n: martes, 28 de junio<\/p>\n<p>Fecha de liquidaci\u00f3n: jueves, 30 de junio<\/p>\n<p>Para ver el aviso oficial, haga\u00a0<a href=\"https:\/\/www.argentina.gob.ar\/noticias\/llamado-licitacion-de-lelites-ledes-lecer-y-bonos-dolar-linked\">click aqu\u00ed<\/a><\/p>\n<p>Detallamos las caracter\u00edsticas de los instrumentos a emitir:<\/p>\n<p><a href=\"https:\/\/www.petrini.com.ar\/en\/nueva-emision-de-letras-y-bonos-del-tesoro-19\/letras-y-bonos-8\/\" rel=\"attachment wp-att-12147\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-12147\" src=\"https:\/\/www.petrini.com.ar\/wp-content\/uploads\/2022\/06\/Letras-y-Bonos-1-1024x256.png\" alt=\"\" width=\"770\" height=\"193\" \/><\/a><\/p>\n<p>Para m\u00e1s informaci\u00f3n:<\/p>\n<ul>\n<li>Ingres\u00e1 a nuestra web\u00a0<a href=\"https:\/\/www.petrini.com.ar\/en\/\">www.petrini.com.ar<\/a>.<\/li>\n<li>Comunicate por tel\u00e9fono: +54 (351) 423-0048 o por email\u00a0<a href=\"mailto:info@petrini.com.ar\">info@petrini.com.ar<\/a><\/li>\n<li>O coordin\u00e1 una reuni\u00f3n en nuestras oficinas comerciales: 25 de Mayo 267 \u2013 Piso 3 \u2013 C\u00f3rdoba, Argentina.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>En esta oportunidad, el Ministerio de Econom\u00eda de la Naci\u00f3n licita Letras en Pesos, Bonos D\u00f3lar Linked y Lecer del Tesoro Nacional. Fecha de licitaci\u00f3n: martes, 28 de junio Fecha de liquidaci\u00f3n: jueves, 30 de junio Para ver el aviso oficial, haga\u00a0click aqu\u00ed Detallamos las caracter\u00edsticas de los instrumentos a emitir: Para m\u00e1s informaci\u00f3n: Ingres\u00e1 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":2904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[101],"tags":[],"class_list":["post-12132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emisiones"],"_links":{"self":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/12132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/comments?post=12132"}],"version-history":[{"count":0,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/posts\/12132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media\/2904"}],"wp:attachment":[{"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/media?parent=12132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/categories?post=12132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.petrini.com.ar\/en\/wp-json\/wp\/v2\/tags?post=12132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}